{"id":34412,"date":"2025-12-17T08:01:43","date_gmt":"2025-12-17T08:01:43","guid":{"rendered":"https:\/\/idi.no\/news-and-events\/news\/los-jovenes-lideres-de-las-efs-construyen-entidades-fiscalizadoras-superiores-efs-fuertes-cuarta-edicion\/"},"modified":"2026-01-21T10:44:03","modified_gmt":"2026-01-21T10:44:03","slug":"los-jovenes-lideres-de-las-efs-construyen-entidades-fiscalizadoras-superiores-efs-fuertes-cuarta-edicion","status":"publish","type":"news","link":"https:\/\/idi.no\/es\/news-and-events\/news\/los-jovenes-lideres-de-las-efs-construyen-entidades-fiscalizadoras-superiores-efs-fuertes-cuarta-edicion\/","title":{"rendered":"Los J\u00f3venes L\u00edderes de las EFS construyen Entidades Fiscalizadoras Superiores (EFS) fuertes &#8211; Cuarta edici\u00f3n"},"content":{"rendered":"\n<div  class=\"article-header-block   block-style-image-type--default\">\n\t<div class=\"article-header-block__container container\">\n\t\t\t\t<div class=\"article-header-block__breadcrumbs\">\n\t\t\t<span><span><a href=\"https:\/\/idi.no\/es\/\">Home<\/a><\/span><\/span>\t\t\t<\/div>\n\t\t\t\t<div class=\"article-header-block__meta \">\n\t\t<div class=\"article-header-block__hero-content\">\n\n\t\t\t\t\t<div class=\"article-header-block__categories \">\n\t\t\t<span class=\"article-header-block__category\">News<\/span>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<h2 class=\"article-header-block__title \">\n\t\t\tLos J\u00f3venes L\u00edderes de las EFS construyen Entidades Fiscalizadoras Superiores (EFS) fuertes &#8211; Cuarta edici\u00f3n<\/h2>\n\t\t\n\t\t\t\t\t<div class=\"article-header-block__date \">\n\t\t\t17\/12\/2025<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"article-header-block__preview \">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1708\" src=\"https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Official-Photo-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Official-Photo-scaled.jpg 2560w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Official-Photo-300x200.jpg 300w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Official-Photo-1024x683.jpg 1024w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Official-Photo-768x512.jpg 768w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Official-Photo-1536x1025.jpg 1536w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Official-Photo-2048x1366.jpg 2048w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Official-Photo-900x600.jpg 900w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/>\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"wp-block-columns alignfull is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"social-share-block\">\n  <span class=\"social-share-block__title\">Share<\/span>\n  <div class=\"social-share-block__icons\">\n    <div class=\"simplesocialbuttons simplesocial-round-icon simplesocialbuttons_inline simplesocialbuttons-align-left simplesocialbuttons-inline-no-animation\">\n<button class=\"simplesocial-fb-share\"  rel=\"nofollow\"  target=\"_blank\"  aria-label=\"Facebook Share\" data-href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/idi.no\/es\/news-and-events\/news\/los-jovenes-lideres-de-las-efs-construyen-entidades-fiscalizadoras-superiores-efs-fuertes-cuarta-edicion\/\" onClick=\"javascript:window.open(this.dataset.href, '', 'menubar=no,toolbar=no,resizable=yes,scrollbars=yes,height=600,width=600');return false;\"><span class=\"simplesocialtxt\">Facebook <\/span> <\/button>\n<button class=\"simplesocial-twt-share\"  rel=\"nofollow\"  target=\"_blank\"  aria-label=\"Twitter Share\" data-href=\"https:\/\/twitter.com\/intent\/tweet?text=Los+J%C3%B3venes+L%C3%ADderes+de+las+EFS+construyen+Entidades+Fiscalizadoras+Superiores+%28EFS%29+fuertes+%E2%80%93+Cuarta+edici%C3%B3n&#038;url=https:\/\/idi.no\/es\/news-and-events\/news\/los-jovenes-lideres-de-las-efs-construyen-entidades-fiscalizadoras-superiores-efs-fuertes-cuarta-edicion\/\" onClick=\"javascript:window.open(this.dataset.href, '', 'menubar=no,toolbar=no,resizable=yes,scrollbars=yes,height=600,width=600');return false;\"><span class=\"simplesocialtxt\">Twitter<\/span> <\/button>\n<button  rel=\"nofollow\"  target=\"_blank\"  class=\"simplesocial-linkedin-share\" aria-label=\"LinkedIn Share\" data-href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https:\/\/idi.no\/es\/news-and-events\/news\/los-jovenes-lideres-de-las-efs-construyen-entidades-fiscalizadoras-superiores-efs-fuertes-cuarta-edicion\/\" onClick=\"javascript:window.open(this.dataset.href, '', 'menubar=no,toolbar=no,resizable=yes,scrollbars=yes,height=600,width=600');return false;\"><span class=\"simplesocialtxt\">LinkedIn<\/span><\/button>\n<button onClick=\"javascript:window.location.href = this.dataset.href;return false;\" class=\"simplesocial-email-share\" aria-label=\"Share through Email\"  rel=\"nofollow\"  target=\"_blank\"   data-href=\"mailto:?subject=Los J%C3%B3venes L%C3%ADderes de las EFS construyen Entidades Fiscalizadoras Superiores %28EFS%29 fuertes %E2%80%93 Cuarta edici%C3%B3n&#038;body=https:\/\/idi.no\/es\/news-and-events\/news\/los-jovenes-lideres-de-las-efs-construyen-entidades-fiscalizadoras-superiores-efs-fuertes-cuarta-edicion\/\"><span class=\"simplesocialtxt\">Email<\/span><\/button>\n<button class=\"simplesocial-copy-link copy-share\"  rel=\"nofollow\"  target=\"_blank\"  aria-label=\"Copy Link\" data-href=\" https:\/\/idi.no\/es\/news-and-events\/news\/los-jovenes-lideres-de-las-efs-construyen-entidades-fiscalizadoras-superiores-efs-fuertes-cuarta-edicion\/\"  onClick=\"ssb_copy_share_link(this); return false;\"><span class=\"simplesocialtxt\">Copy<\/span><span class=\"ssb_tooltip\">Copied<\/span> <\/button>\n<\/div>\n  <\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\r\n<div  class=\"text-only-block text-only-block__text-only\"> <!-- Removed undefined $style (before: echoed $style) -->\r\n    <div class=\"text-only-block__container container\">\r\n                    <div class=\"text-only-block__content\">\r\n                                    <h2 class=\"text-only-block__title\">Los J\u00f3venes L\u00edderes de las EFS construyen Entidades Fiscalizadoras Superiores (EFS) fuertes<\/h2>\r\n                                                                    <div class=\"text-only-block__description\"><p>Mascate acoge la cuarta edici\u00f3n de la iniciativa J\u00f3venes L\u00edderes de la EFS, que se prolongar\u00e1 hasta el 12 de diciembre de 2025.<\/p>\n<p>El liderazgo no es un t\u00edtulo ni una etapa; es un viaje de crecimiento y transformaci\u00f3n. A lo largo del a\u00f1o pasado, los J\u00f3venes L\u00edderes emprendieron un intenso viaje de desarrollo que les desafi\u00f3 a reflexionar, evolucionar y liderar con determinaci\u00f3n en un entorno del sector p\u00fablico cada vez m\u00e1s complejo. <\/p>\n<p>Como una de las iniciativas emblem\u00e1ticas de la IDI, capacita a los l\u00edderes emergentes de las EFS con modernas herramientas de liderazgo, metodolog\u00edas pr\u00e1cticas, s\u00f3lidas habilidades de colaboraci\u00f3n y perspectivas de futuro sobre la fiscalizaci\u00f3n del sector p\u00fablico.<\/p>\n<p>A lo largo del programa de un a\u00f1o de duraci\u00f3n, los participantes progresaron a trav\u00e9s de cuatro pilares de aprendizaje interconectados:<\/p>\n<p>\ud83d\udd0d Descubrirse a uno mismo &#8211; desarrollar la autoconciencia, el liderazgo \u00e9tico y la resiliencia personal<br \/>\n\ud83d\udc65 Dirigir a las personas &#8211; reforzar la comunicaci\u00f3n, el trabajo en equipo y las capacidades de liderazgo inclusivo<br \/>\n\ud83c\udf10 Descubrir el universo &#8211; comprender las tendencias globales, la transformaci\u00f3n digital y el papel cambiante de las EFS<br \/>\n\ud83c\udfaf Aportar valor &#8211; traducir el liderazgo en impacto, relevancia y valor p\u00fablico para los ciudadanos<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-33267\" src=\"https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-5-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-5-1024x683.jpg 1024w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-5-300x200.jpg 300w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-5-768x512.jpg 768w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-5-1536x1025.jpg 1536w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-5-2048x1366.jpg 2048w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-5-900x600.jpg 900w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-33272\" src=\"https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-10-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-10-1024x683.jpg 1024w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-10-300x200.jpg 300w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-10-768x512.jpg 768w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-10-1536x1025.jpg 1536w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-10-2048x1366.jpg 2048w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-10-900x600.jpg 900w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<h6><em>La conferencia fue inaugurada por la Autoridad Estatal de Auditor\u00eda Financiera y Administrativa, el Sr. Khalid Saif Khalaf Al Kharusi, Jefe de la Oficina del Presidente, y la Sra. Archana Shirsat, Directora General Adjunta de la IDI.<\/em><\/h6>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-33273\" src=\"https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-11-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-11-1024x683.jpg 1024w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-11-300x200.jpg 300w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-11-768x512.jpg 768w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-11-1536x1025.jpg 1536w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-11-2048x1366.jpg 2048w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-11-900x600.jpg 900w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<h6><em>El Sr. Said Salim Said Al Hajri, Jefe de Relaciones Internacionales de la EFS de Om\u00e1n, hizo una presentaci\u00f3n sobre el mandato de la Autoridad Estatal de Auditor\u00eda Financiera y Administrativa, que incluye un mandato ampliado de lucha contra la corrupci\u00f3n.<\/em><\/h6>\n<p>Equipada con modernas herramientas de liderazgo, metodolog\u00edas pr\u00e1cticas, s\u00f3lidas habilidades de colaboraci\u00f3n y visiones de futuro sobre la fiscalizaci\u00f3n del sector p\u00fablico, la pr\u00f3xima generaci\u00f3n de l\u00edderes de las EFS estar\u00e1 preparada para crear impacto en todo el mundo.<\/p>\n<p>Extendemos nuestro sincero agradecimiento a nuestro anfitri\u00f3n, la Autoridad Estatal de Auditor\u00eda Financiera y Administrativa (EFS de Om\u00e1n), por su firme compromiso con el avance de la profesi\u00f3n auditora y la inversi\u00f3n en la pr\u00f3xima generaci\u00f3n de l\u00edderes de las EFS.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-33270\" src=\"https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-8-1024x683.jpg\" alt=\"\" width=\"263\" height=\"175\" srcset=\"https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-8-1024x683.jpg 1024w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-8-300x200.jpg 300w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-8-768x512.jpg 768w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-8-1536x1025.jpg 1536w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-8-2048x1366.jpg 2048w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-8-900x600.jpg 900w\" sizes=\"auto, (max-width: 263px) 100vw, 263px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-33269\" src=\"https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-7-1024x683.jpg\" alt=\"\" width=\"260\" height=\"173\" srcset=\"https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-7-1024x683.jpg 1024w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-7-300x200.jpg 300w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-7-768x512.jpg 768w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-7-1536x1025.jpg 1536w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-7-2048x1366.jpg 2048w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-7-900x600.jpg 900w\" sizes=\"auto, (max-width: 260px) 100vw, 260px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-33268\" src=\"https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-6-1024x683.jpg\" alt=\"\" width=\"260\" height=\"174\" srcset=\"https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-6-1024x683.jpg 1024w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-6-300x200.jpg 300w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-6-768x512.jpg 768w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-6-1536x1025.jpg 1536w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-6-2048x1366.jpg 2048w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-6-900x600.jpg 900w\" sizes=\"auto, (max-width: 260px) 100vw, 260px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-33264\" src=\"https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-3-1024x683.jpg\" alt=\"\" width=\"263\" height=\"175\" srcset=\"https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-3-1024x683.jpg 1024w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-3-300x200.jpg 300w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-3-768x512.jpg 768w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-3-1536x1025.jpg 1536w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-3-2048x1366.jpg 2048w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-3-900x600.jpg 900w\" sizes=\"auto, (max-width: 263px) 100vw, 263px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-33263\" src=\"https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-2-1024x683.jpg\" alt=\"\" width=\"261\" height=\"174\" srcset=\"https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-2-1024x683.jpg 1024w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-2-300x200.jpg 300w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-2-768x512.jpg 768w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-2-1536x1025.jpg 1536w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-2-2048x1366.jpg 2048w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-2-900x600.jpg 900w\" sizes=\"auto, (max-width: 261px) 100vw, 261px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-33266\" src=\"https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-5-2-1024x683.jpg\" alt=\"\" width=\"261\" height=\"174\" srcset=\"https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-5-2-1024x683.jpg 1024w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-5-2-300x200.jpg 300w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-5-2-768x512.jpg 768w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-5-2-1536x1025.jpg 1536w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-5-2-2048x1366.jpg 2048w, https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Oman-5-2-900x600.jpg 900w\" sizes=\"auto, (max-width: 261px) 100vw, 261px\" \/><\/p>\n<p>Para saber m\u00e1s sobre esta iniciativa, consulta nuestra <a href=\"https:\/\/idi.no\/es\/our-work\/initiative\/jovenes-lideres-de-efs-syl\/\">p\u00e1gina SAI J\u00f3venes L\u00edderes.<\/a><\/p>\n<\/div>\r\n                                \r\n                <!-- New: Wrap all buttons in __button-list for consistency with working block -->\r\n                <div class=\"text-only-block__button-list\">\r\n                    \r\n                                    <\/div>\r\n            <\/div>\r\n        \r\n        \r\n        \r\n            <\/div>\r\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n<div  class=\"initiatives-topics-block \">\n  <div class=\"initiatives-topics-block__container container\">\n    <div class=\"initiatives-topics-block__initiatives initiatives-topics-block__column \">\n      <h3>Initiative<\/h3>\n      <div class=\"initiatives-topics-block__terms \">\n        <span class=\"initiatives-topics-block__terms_term \">SYL \u2013 SAI Young Leaders<\/span>      <\/div>\n    <\/div>\n\n    <div class=\"initiatives-topics-block__topics initiatives-topics-block__column \">\n      <h3>Topics<\/h3>\n      <div class=\"initiatives-topics-block__terms \">\n        <span class=\"initiatives-topics-block__terms_term \">Leadership<\/span>      <\/div>\n    <\/div>\n  <\/div>\n<\/div>    <div         class=\"event-news-grid-block block-background-color--white\">\r\n        <div class=\"event-news-grid-block__container container\">\r\n            <h2 class=\"event-news-grid-block__label\">Noticias recientes<\/h2>\r\n            <div class=\"event-news-grid-block__grid\">\r\n                    <div class=\"news-card\">\r\n        <a  href=\"https:\/\/idi.no\/es\/news-and-events\/news\/comienza-un-nuevo-capitulo-la-efs-de-uzbekistan-se-une-a-la-iniciativa-global-para-la-rendicion-de-cuentas-de-las-efs-gsai-2\/\"\r\n            class=\"news-card__full-card-link\"\r\n            data-uw-ignore-s3\r\n        ><\/a>\r\n                    <span class=\"event-card__image-container\"><img decoding=\"async\" src=\"https:\/\/idi.no\/wp-content\/uploads\/2026\/04\/CASAI-Press-release-cover.png\" alt=\"Comienza un nuevo cap\u00edtulo: La EFS de Uzbekist\u00e1n se une a la Iniciativa Global para la Rendici\u00f3n de Cuentas de las EFS (GSAI)\" class=\"news-card__image\"><\/span>\r\n                            <div class=\"news-card__categories\"><a href=\"https:\/\/idi.no\/es\/news\/\">News<\/a><\/div>\r\n                            <div class=\"news-card__date\">22\/04\/2026<\/div>\r\n                            <h6 class=\"news-card__title\">Comienza un nuevo cap\u00edtulo: La EFS de Uzbekist\u00e1n se une a la Iniciativa Global para la Rendici\u00f3n de Cuentas de las EFS (GSAI)<\/h6>\r\n                        <a href=\"https:\/\/idi.no\/es\/news-and-events\/news\/comienza-un-nuevo-capitulo-la-efs-de-uzbekistan-se-une-a-la-iniciativa-global-para-la-rendicion-de-cuentas-de-las-efs-gsai-2\/\" class=\"news-card__link\">Read more<\/a>\r\n    <\/div>\r\n        <div class=\"news-card\">\r\n        <a  href=\"https:\/\/idi.no\/es\/news-and-events\/news\/la-idi-y-el-interventor-y-auditor-general-de-la-india-firman-una-vision-compartida-para-el-futuro-2\/\"\r\n            class=\"news-card__full-card-link\"\r\n            data-uw-ignore-s3\r\n        ><\/a>\r\n                    <span class=\"event-card__image-container\"><img decoding=\"async\" src=\"https:\/\/idi.no\/wp-content\/uploads\/2026\/04\/IMG_8372.jpeg\" alt=\"La IDI y el Interventor y Auditor General de la India firman una visi\u00f3n compartida para el futuro\" class=\"news-card__image\"><\/span>\r\n                            <div class=\"news-card__categories\"><a href=\"https:\/\/idi.no\/es\/news\/\">News<\/a><\/div>\r\n                            <div class=\"news-card__date\">13\/04\/2026<\/div>\r\n                            <h6 class=\"news-card__title\">La IDI y el Interventor y Auditor General de la India firman una visi\u00f3n compartida para el futuro<\/h6>\r\n                        <a href=\"https:\/\/idi.no\/es\/news-and-events\/news\/la-idi-y-el-interventor-y-auditor-general-de-la-india-firman-una-vision-compartida-para-el-futuro-2\/\" class=\"news-card__link\">Read more<\/a>\r\n    <\/div>\r\n        <div class=\"news-card\">\r\n        <a  href=\"https:\/\/idi.no\/es\/news-and-events\/news\/la-idi-y-el-interventor-y-auditor-general-de-la-india-firman-una-vision-compartida-para-el-futuro\/\"\r\n            class=\"news-card__full-card-link\"\r\n            data-uw-ignore-s3\r\n        ><\/a>\r\n                    <span class=\"event-card__image-container\"><img decoding=\"async\" src=\"https:\/\/idi.no\/wp-content\/uploads\/2026\/03\/Press-release-1200-x-720px.png\" alt=\"La IDI y el Interventor y Auditor General de la India firman una visi\u00f3n compartida para el futuro\" class=\"news-card__image\"><\/span>\r\n                            <div class=\"news-card__categories\"><a href=\"https:\/\/idi.no\/es\/news\/\">News<\/a><\/div>\r\n                            <div class=\"news-card__date\">24\/03\/2026<\/div>\r\n                            <h6 class=\"news-card__title\">La IDI y el Interventor y Auditor General de la India firman una visi\u00f3n compartida para el futuro<\/h6>\r\n                        <a href=\"https:\/\/idi.no\/es\/news-and-events\/news\/la-idi-y-el-interventor-y-auditor-general-de-la-india-firman-una-vision-compartida-para-el-futuro\/\" class=\"news-card__link\">Read more<\/a>\r\n    <\/div>\r\n        <div class=\"news-card\">\r\n        <a  href=\"https:\/\/idi.no\/es\/news-and-events\/news\/la-direccion-de-las-entidades-fiscalizadoras-superiores-reflexiona-sobre-los-avances-en-las-practicas-sostenibles-de-auditoria-de-gestion-centrandose-en-la-calidad-y-el-impacto-de-la-auditoria-2\/\"\r\n            class=\"news-card__full-card-link\"\r\n            data-uw-ignore-s3\r\n        ><\/a>\r\n                    <span class=\"event-card__image-container\"><img decoding=\"async\" src=\"https:\/\/idi.no\/wp-content\/uploads\/2026\/03\/Official.jpg\" alt=\"La direcci\u00f3n de las Entidades Fiscalizadoras Superiores reflexiona sobre los avances en las pr\u00e1cticas sostenibles de auditor\u00eda de gesti\u00f3n, centr\u00e1ndose en la calidad y el impacto de la auditor\u00eda\" class=\"news-card__image\"><\/span>\r\n                            <div class=\"news-card__categories\"><a href=\"https:\/\/idi.no\/es\/news\/\">News<\/a><\/div>\r\n                            <div class=\"news-card__date\">17\/03\/2026<\/div>\r\n                            <h6 class=\"news-card__title\">La direcci\u00f3n de las Entidades Fiscalizadoras Superiores reflexiona sobre los avances en las pr\u00e1cticas sostenibles de auditor\u00eda de gesti\u00f3n, centr\u00e1ndose en la calidad y el impacto de la auditor\u00eda<\/h6>\r\n                        <a href=\"https:\/\/idi.no\/es\/news-and-events\/news\/la-direccion-de-las-entidades-fiscalizadoras-superiores-reflexiona-sobre-los-avances-en-las-practicas-sostenibles-de-auditoria-de-gestion-centrandose-en-la-calidad-y-el-impacto-de-la-auditoria-2\/\" class=\"news-card__link\">Read more<\/a>\r\n    <\/div>\r\n                <\/div>\r\n                            <div class=\"event-news-grid-block__footer block-footer\">\r\n                                        <a  href=\"\/news-events\/news\/\" \r\n                        class=\"button button--primary\"\r\n                                            >\r\n                        See more                    <\/a>\r\n                <\/div>\r\n                    <\/div>\r\n    <\/div>\r\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":34416,"template":"","content-type":[14],"topic":[21],"initiative":[252],"class_list":["post-34412","news","type-news","status-publish","has-post-thumbnail","hentry","content-type-news","topic-leadership","initiative-syl"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los J\u00f3venes L\u00edderes de las EFS construyen Entidades Fiscalizadoras Superiores (EFS) fuertes - Cuarta edici\u00f3n - IDI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/idi.no\/es\/news-and-events\/news\/los-jovenes-lideres-de-las-efs-construyen-entidades-fiscalizadoras-superiores-efs-fuertes-cuarta-edicion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los J\u00f3venes L\u00edderes de las EFS construyen Entidades Fiscalizadoras Superiores (EFS) fuertes - Cuarta edici\u00f3n - IDI\" \/>\n<meta property=\"og:url\" content=\"https:\/\/idi.no\/es\/news-and-events\/news\/los-jovenes-lideres-de-las-efs-construyen-entidades-fiscalizadoras-superiores-efs-fuertes-cuarta-edicion\/\" \/>\n<meta property=\"og:site_name\" content=\"IDI\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-21T10:44:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Official-Photo-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1708\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/idi.no\\\/es\\\/news-and-events\\\/news\\\/los-jovenes-lideres-de-las-efs-construyen-entidades-fiscalizadoras-superiores-efs-fuertes-cuarta-edicion\\\/\",\"url\":\"https:\\\/\\\/idi.no\\\/es\\\/news-and-events\\\/news\\\/los-jovenes-lideres-de-las-efs-construyen-entidades-fiscalizadoras-superiores-efs-fuertes-cuarta-edicion\\\/\",\"name\":\"Los J\u00f3venes L\u00edderes de las EFS construyen Entidades Fiscalizadoras Superiores (EFS) fuertes - Cuarta edici\u00f3n - IDI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/idi.no\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/idi.no\\\/es\\\/news-and-events\\\/news\\\/los-jovenes-lideres-de-las-efs-construyen-entidades-fiscalizadoras-superiores-efs-fuertes-cuarta-edicion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/idi.no\\\/es\\\/news-and-events\\\/news\\\/los-jovenes-lideres-de-las-efs-construyen-entidades-fiscalizadoras-superiores-efs-fuertes-cuarta-edicion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/idi.no\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/SYL-Official-Photo-scaled.jpg\",\"datePublished\":\"2025-12-17T08:01:43+00:00\",\"dateModified\":\"2026-01-21T10:44:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/idi.no\\\/es\\\/news-and-events\\\/news\\\/los-jovenes-lideres-de-las-efs-construyen-entidades-fiscalizadoras-superiores-efs-fuertes-cuarta-edicion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/idi.no\\\/es\\\/news-and-events\\\/news\\\/los-jovenes-lideres-de-las-efs-construyen-entidades-fiscalizadoras-superiores-efs-fuertes-cuarta-edicion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/idi.no\\\/es\\\/news-and-events\\\/news\\\/los-jovenes-lideres-de-las-efs-construyen-entidades-fiscalizadoras-superiores-efs-fuertes-cuarta-edicion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/idi.no\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/SYL-Official-Photo-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/idi.no\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/SYL-Official-Photo-scaled.jpg\",\"width\":2560,\"height\":1708},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/idi.no\\\/es\\\/news-and-events\\\/news\\\/los-jovenes-lideres-de-las-efs-construyen-entidades-fiscalizadoras-superiores-efs-fuertes-cuarta-edicion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/idi.no\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los J\u00f3venes L\u00edderes de las EFS construyen Entidades Fiscalizadoras...\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/idi.no\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/idi.no\\\/es\\\/\",\"name\":\"IDI\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/idi.no\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los J\u00f3venes L\u00edderes de las EFS construyen Entidades Fiscalizadoras Superiores (EFS) fuertes - Cuarta edici\u00f3n - IDI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/idi.no\/es\/news-and-events\/news\/los-jovenes-lideres-de-las-efs-construyen-entidades-fiscalizadoras-superiores-efs-fuertes-cuarta-edicion\/","og_locale":"es_ES","og_type":"article","og_title":"Los J\u00f3venes L\u00edderes de las EFS construyen Entidades Fiscalizadoras Superiores (EFS) fuertes - Cuarta edici\u00f3n - IDI","og_url":"https:\/\/idi.no\/es\/news-and-events\/news\/los-jovenes-lideres-de-las-efs-construyen-entidades-fiscalizadoras-superiores-efs-fuertes-cuarta-edicion\/","og_site_name":"IDI","article_modified_time":"2026-01-21T10:44:03+00:00","og_image":[{"width":2560,"height":1708,"url":"https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Official-Photo-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/idi.no\/es\/news-and-events\/news\/los-jovenes-lideres-de-las-efs-construyen-entidades-fiscalizadoras-superiores-efs-fuertes-cuarta-edicion\/","url":"https:\/\/idi.no\/es\/news-and-events\/news\/los-jovenes-lideres-de-las-efs-construyen-entidades-fiscalizadoras-superiores-efs-fuertes-cuarta-edicion\/","name":"Los J\u00f3venes L\u00edderes de las EFS construyen Entidades Fiscalizadoras Superiores (EFS) fuertes - Cuarta edici\u00f3n - IDI","isPartOf":{"@id":"https:\/\/idi.no\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/idi.no\/es\/news-and-events\/news\/los-jovenes-lideres-de-las-efs-construyen-entidades-fiscalizadoras-superiores-efs-fuertes-cuarta-edicion\/#primaryimage"},"image":{"@id":"https:\/\/idi.no\/es\/news-and-events\/news\/los-jovenes-lideres-de-las-efs-construyen-entidades-fiscalizadoras-superiores-efs-fuertes-cuarta-edicion\/#primaryimage"},"thumbnailUrl":"https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Official-Photo-scaled.jpg","datePublished":"2025-12-17T08:01:43+00:00","dateModified":"2026-01-21T10:44:03+00:00","breadcrumb":{"@id":"https:\/\/idi.no\/es\/news-and-events\/news\/los-jovenes-lideres-de-las-efs-construyen-entidades-fiscalizadoras-superiores-efs-fuertes-cuarta-edicion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/idi.no\/es\/news-and-events\/news\/los-jovenes-lideres-de-las-efs-construyen-entidades-fiscalizadoras-superiores-efs-fuertes-cuarta-edicion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/idi.no\/es\/news-and-events\/news\/los-jovenes-lideres-de-las-efs-construyen-entidades-fiscalizadoras-superiores-efs-fuertes-cuarta-edicion\/#primaryimage","url":"https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Official-Photo-scaled.jpg","contentUrl":"https:\/\/idi.no\/wp-content\/uploads\/2025\/12\/SYL-Official-Photo-scaled.jpg","width":2560,"height":1708},{"@type":"BreadcrumbList","@id":"https:\/\/idi.no\/es\/news-and-events\/news\/los-jovenes-lideres-de-las-efs-construyen-entidades-fiscalizadoras-superiores-efs-fuertes-cuarta-edicion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/idi.no\/es\/"},{"@type":"ListItem","position":2,"name":"Los J\u00f3venes L\u00edderes de las EFS construyen Entidades Fiscalizadoras..."}]},{"@type":"WebSite","@id":"https:\/\/idi.no\/es\/#website","url":"https:\/\/idi.no\/es\/","name":"IDI","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/idi.no\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/idi.no\/es\/wp-json\/wp\/v2\/news\/34412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/idi.no\/es\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/idi.no\/es\/wp-json\/wp\/v2\/types\/news"}],"version-history":[{"count":1,"href":"https:\/\/idi.no\/es\/wp-json\/wp\/v2\/news\/34412\/revisions"}],"predecessor-version":[{"id":34430,"href":"https:\/\/idi.no\/es\/wp-json\/wp\/v2\/news\/34412\/revisions\/34430"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/idi.no\/es\/wp-json\/wp\/v2\/media\/34416"}],"wp:attachment":[{"href":"https:\/\/idi.no\/es\/wp-json\/wp\/v2\/media?parent=34412"}],"wp:term":[{"taxonomy":"content-type","embeddable":true,"href":"https:\/\/idi.no\/es\/wp-json\/wp\/v2\/content-type?post=34412"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/idi.no\/es\/wp-json\/wp\/v2\/topic?post=34412"},{"taxonomy":"initiative","embeddable":true,"href":"https:\/\/idi.no\/es\/wp-json\/wp\/v2\/initiative?post=34412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}